{"id":6370,"date":"2026-04-22T18:00:43","date_gmt":"2026-04-22T21:00:43","guid":{"rendered":"https:\/\/abbabrasil.org.br\/?p=6370"},"modified":"2026-05-12T13:08:19","modified_gmt":"2026-05-12T16:08:19","slug":"aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras","status":"publish","type":"post","link":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/","title":{"rendered":"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Processo de chegada e forma\u00e7\u00e3o de novas fam\u00edlias acolhedoras<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui no Servi\u00e7o de Acolhimento em Fam\u00edlia Acolhedora P\u00e9rolas Santo Amaro, \u00e9 sempre uma alegria para a equipe t\u00e9cnica receber novas turmas para forma\u00e7\u00e3o de fam\u00edlias acolhedoras, pois elas s\u00e3o parte fundamental do nosso servi\u00e7o. Elas ir\u00e3o acolher temporariamente crian\u00e7as e\/ou adolescentes que se encontram em medida protetiva, oferecendo cuidado, prote\u00e7\u00e3o integral e conviv\u00eancia familiar e comunit\u00e1ria, em suas resid\u00eancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acolhimento familiar \u00e9 uma pol\u00edtica p\u00fablica que depende diretamente da participa\u00e7\u00e3o da sociedade. Por essa raz\u00e3o, um dos nossos desafios \u00e9 encontrar fam\u00edlias com o perfil e a disponibilidade para atender \u00e0 demanda deste servi\u00e7o de acolhimento. Durante o acolhimento a fam\u00edlia acolhedora assume todos os cuidados di\u00e1rios da crian\u00e7a e\/ou adolescente, oferecendo amor, afeto e prote\u00e7\u00e3o na conviv\u00eancia familiar, com muito aprendizado e comprometimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quanto ao processo de chegada e forma\u00e7\u00e3o de novas fam\u00edlias acolhedoras, este se inicia com a divulga\u00e7\u00e3o, sensibiliza\u00e7\u00e3o e apresenta\u00e7\u00e3o do servi\u00e7o, de seus objetivos, dos crit\u00e9rios e as responsabilidades relacionadas ao acolhimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s a manifesta\u00e7\u00e3o de interesse e a participa\u00e7\u00e3o em reuni\u00e3o informativa, a fam\u00edlia \u00e9 inserida no processo de avalia\u00e7\u00e3o, conduzida pela equipe t\u00e9cnica com assistente social e psic\u00f3logo. Ap\u00f3s esta etapa, tem a entrega da documenta\u00e7\u00e3o&nbsp; exigida, formul\u00e1rios devidamente preenchidos e uma entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na sequ\u00eancia, as fam\u00edlias participam do processo formativo de capacita\u00e7\u00e3o, com conte\u00fado programado e car\u00e1ter reflexivo, abordando aspectos t\u00e9cnicos, jur\u00eddicos, \u00e9ticos e emocionais relacionados \u00e0 medida protetiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, s\u00e3o realizadas uma visita domiciliar, estudo psicossocial, avalia\u00e7\u00e3o t\u00e9cnica e aprova\u00e7\u00e3o final para habilita\u00e7\u00e3o no servi\u00e7o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante ressaltar que durante todo o per\u00edodo de acolhimento a equipe t\u00e9cnica mant\u00e9m acompanhamento cont\u00ednuo junto \u00e0s fam\u00edlias acolhedoras, \u00e0s crian\u00e7as acolhidas e \u00e0s fam\u00edlias de origem, com atendimentos, visitas domiciliares, reuni\u00f5es e articula\u00e7\u00e3o com a rede de servi\u00e7os, assegurando a efetividade da medida de prote\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Servi\u00e7o de Fam\u00edlia Acolhedora atua em conformidade com o Estatuto da Crian\u00e7a e do Adolescente (ECA), favorecendo o cuidado e prote\u00e7\u00e3o integral e a garantia do direito \u00e0 conviv\u00eancia familiar e comunit\u00e1ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <strong>art. 19 do ECA<\/strong> assegura \u00e0 crian\u00e7a e ao adolescente o direito \u00e0 conviv\u00eancia familiar e comunit\u00e1ria, sendo garantido o desenvolvimento em ambiente que promova sua prote\u00e7\u00e3o integral, dignidade e bem-estar, bem como o direito de ser criado e educado no seio de sua fam\u00edlia e, excepcionalmente, em fam\u00edlia substituta, sempre resguardados seus direitos fundamentais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, seguimos com este trabalho desafiador mas cheio de alegrias, no objetivo de transformar hist\u00f3rias juntamente com estas fam\u00edlias que se dedicam com tanto amor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inclu\u00edmos aqui, ainda, breve relato de um casal participante da capacita\u00e7\u00e3o&nbsp; de novas fam\u00edlias acolhedoras, realizada neste semestre&nbsp;<\/p>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"border-left-color:#7c7e33;border-left-width:5px;background-color:#f9f8f3\"><em>\u201cMeu nome \u00e9 Amanda Lucena. Quero agradecer a toda a equipe t\u00e9cnica; fazer parte dessa capacita\u00e7\u00e3o me fez adquirir muito conhecimento ao longo de cada m\u00f3dulo. Fui aprendendo e buscando informa\u00e7\u00f5es sobre os assuntos. Sei que n\u00e3o para por aqui e que j\u00e1 sou uma pessoa diferente do in\u00edcio da capacita\u00e7\u00e3o. Uma mulher com olhar mais atento e generoso. Sei que terei desafios, mas j\u00e1 me sinto grande antes de acolher e acredito que no processo de acolhimento serei bem maior. Gratid\u00e3o \u00e9 a palavra que define esse momento da minha vida.\u201d<\/em><\/p>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"border-left-color:#7c7e33;border-left-width:5px;background-color:#f9f8f3\"><em>\u201cPrazer, meu nome \u00e9 Anderson. Tive a oportunidade de conhecer o projeto por meio da minha esposa e, ao longo do treinamento conduzido com excel\u00eancia pela equipe t\u00e9cnica pude compreender mais profundamente a hist\u00f3ria do acolhimento, do cuidado e da ado\u00e7\u00e3o no Brasil.<\/em><br><em><br>Sei que esse \u00e9 um caminho longo de aprendizado cont\u00ednuo, mas observar a dedica\u00e7\u00e3o e o amor com que o projeto cuida de crian\u00e7as que j\u00e1 enfrentaram tantas dificuldades \u00e9 algo que me enche de alegria e esperan\u00e7a.<\/em><br><em><br>Desejo continuar fazendo parte dessa iniciativa e, em breve, poder impactar positivamente a vida de algu\u00e9m. Confesso que me surpreende n\u00e3o haver filas de fam\u00edlias interessadas em participar desse trabalho t\u00e3o transformador. Na minha vis\u00e3o, somos n\u00f3s os maiores beneficiados por termos a oportunidade de cuidar, acolher e oferecer o nosso melhor a essas crian\u00e7as e, se Deus permitir, por muito tempo.\u201d<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Processo de chegada e forma\u00e7\u00e3o de novas fam\u00edlias acolhedoras Aqui no Servi\u00e7o de Acolhimento em Fam\u00edlia Acolhedora P\u00e9rolas Santo Amaro, [&hellip;]<\/p>\n","protected":false},"author":624,"featured_media":6374,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-6370","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espaco-tecnico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras | ABBA Brasil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras | ABBA Brasil\" \/>\n<meta property=\"og:description\" content=\"Processo de chegada e forma\u00e7\u00e3o de novas fam\u00edlias acolhedoras Aqui no Servi\u00e7o de Acolhimento em Fam\u00edlia Acolhedora P\u00e9rolas Santo Amaro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/\" \/>\n<meta property=\"og:site_name\" content=\"ABBA Brasil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AssociacaoBrasileiraBeneficenteAslan\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-22T21:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T16:08:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2026\/04\/silhueta-familia-por-do-sol-janela.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Valdenise\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valdenise\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/\"},\"author\":{\"name\":\"Valdenise\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#\\\/schema\\\/person\\\/dfae81092d62162626cfbc98e7971a57\"},\"headline\":\"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras\",\"datePublished\":\"2026-04-22T21:00:43+00:00\",\"dateModified\":\"2026-05-12T16:08:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/\"},\"wordCount\":780,\"publisher\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/silhueta-familia-por-do-sol-janela.webp\",\"articleSection\":[\"Espa\u00e7o t\u00e9cnico\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/\",\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/\",\"name\":\"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras | ABBA Brasil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/silhueta-familia-por-do-sol-janela.webp\",\"datePublished\":\"2026-04-22T21:00:43+00:00\",\"dateModified\":\"2026-05-12T16:08:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/silhueta-familia-por-do-sol-janela.webp\",\"contentUrl\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/silhueta-familia-por-do-sol-janela.webp\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/blog\\\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/abbabrasil.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/\",\"name\":\"Abba Brasil\",\"description\":\"Servindo crian\u00e7as, adolescentes e jovens\",\"publisher\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#organization\"},\"alternateName\":\"Abba\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#organization\",\"name\":\"Abba\",\"alternateName\":\"Abba\",\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-favicon-abba.webp\",\"contentUrl\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/cropped-favicon-abba.webp\",\"width\":512,\"height\":512,\"caption\":\"Abba\"},\"image\":{\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AssociacaoBrasileiraBeneficenteAslan\",\"https:\\\/\\\/www.instagram.com\\\/abba.brasil\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/#\\\/schema\\\/person\\\/dfae81092d62162626cfbc98e7971a57\",\"name\":\"Valdenise\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/litespeed\\\/avatar\\\/877f98369dd1cdb844314f805a6a4eea.jpg?ver=1783552766\",\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/litespeed\\\/avatar\\\/877f98369dd1cdb844314f805a6a4eea.jpg?ver=1783552766\",\"contentUrl\":\"https:\\\/\\\/abbabrasil.org.br\\\/wp-content\\\/litespeed\\\/avatar\\\/877f98369dd1cdb844314f805a6a4eea.jpg?ver=1783552766\",\"caption\":\"Valdenise\"},\"url\":\"https:\\\/\\\/abbabrasil.org.br\\\/en\\\/author\\\/valdenise\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras | ABBA Brasil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/","og_locale":"en_US","og_type":"article","og_title":"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras | ABBA Brasil","og_description":"Processo de chegada e forma\u00e7\u00e3o de novas fam\u00edlias acolhedoras Aqui no Servi\u00e7o de Acolhimento em Fam\u00edlia Acolhedora P\u00e9rolas Santo Amaro, [&hellip;]","og_url":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/","og_site_name":"ABBA Brasil","article_publisher":"https:\/\/www.facebook.com\/AssociacaoBrasileiraBeneficenteAslan","article_published_time":"2026-04-22T21:00:43+00:00","article_modified_time":"2026-05-12T16:08:19+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2026\/04\/silhueta-familia-por-do-sol-janela.webp","type":"image\/webp"}],"author":"Valdenise","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Valdenise","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#article","isPartOf":{"@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/"},"author":{"name":"Valdenise","@id":"https:\/\/abbabrasil.org.br\/en\/#\/schema\/person\/dfae81092d62162626cfbc98e7971a57"},"headline":"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras","datePublished":"2026-04-22T21:00:43+00:00","dateModified":"2026-05-12T16:08:19+00:00","mainEntityOfPage":{"@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/"},"wordCount":780,"publisher":{"@id":"https:\/\/abbabrasil.org.br\/en\/#organization"},"image":{"@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#primaryimage"},"thumbnailUrl":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2026\/04\/silhueta-familia-por-do-sol-janela.webp","articleSection":["Espa\u00e7o t\u00e9cnico"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/","url":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/","name":"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras | ABBA Brasil","isPartOf":{"@id":"https:\/\/abbabrasil.org.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#primaryimage"},"image":{"@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#primaryimage"},"thumbnailUrl":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2026\/04\/silhueta-familia-por-do-sol-janela.webp","datePublished":"2026-04-22T21:00:43+00:00","dateModified":"2026-05-12T16:08:19+00:00","breadcrumb":{"@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#primaryimage","url":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2026\/04\/silhueta-familia-por-do-sol-janela.webp","contentUrl":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2026\/04\/silhueta-familia-por-do-sol-janela.webp","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/abbabrasil.org.br\/en\/blog\/aconteceu-no-perolas-formacao-de-novas-familias-acolhedoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/abbabrasil.org.br\/"},{"@type":"ListItem","position":2,"name":"Aconteceu no P\u00e9rolas: Forma\u00e7\u00e3o de Novas Fam\u00edlias Acolhedoras"}]},{"@type":"WebSite","@id":"https:\/\/abbabrasil.org.br\/en\/#website","url":"https:\/\/abbabrasil.org.br\/en\/","name":"Abba Brasil","description":"Servindo crian\u00e7as, adolescentes e jovens","publisher":{"@id":"https:\/\/abbabrasil.org.br\/en\/#organization"},"alternateName":"Abba","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abbabrasil.org.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/abbabrasil.org.br\/en\/#organization","name":"Abba","alternateName":"Abba","url":"https:\/\/abbabrasil.org.br\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/abbabrasil.org.br\/en\/#\/schema\/logo\/image\/","url":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2023\/11\/cropped-favicon-abba.webp","contentUrl":"https:\/\/abbabrasil.org.br\/wp-content\/uploads\/2023\/11\/cropped-favicon-abba.webp","width":512,"height":512,"caption":"Abba"},"image":{"@id":"https:\/\/abbabrasil.org.br\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AssociacaoBrasileiraBeneficenteAslan","https:\/\/www.instagram.com\/abba.brasil\/"]},{"@type":"Person","@id":"https:\/\/abbabrasil.org.br\/en\/#\/schema\/person\/dfae81092d62162626cfbc98e7971a57","name":"Valdenise","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/abbabrasil.org.br\/wp-content\/litespeed\/avatar\/877f98369dd1cdb844314f805a6a4eea.jpg?ver=1783552766","url":"https:\/\/abbabrasil.org.br\/wp-content\/litespeed\/avatar\/877f98369dd1cdb844314f805a6a4eea.jpg?ver=1783552766","contentUrl":"https:\/\/abbabrasil.org.br\/wp-content\/litespeed\/avatar\/877f98369dd1cdb844314f805a6a4eea.jpg?ver=1783552766","caption":"Valdenise"},"url":"https:\/\/abbabrasil.org.br\/en\/author\/valdenise\/"}]}},"_links":{"self":[{"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/posts\/6370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/users\/624"}],"replies":[{"embeddable":true,"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/comments?post=6370"}],"version-history":[{"count":0,"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/posts\/6370\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/media\/6374"}],"wp:attachment":[{"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/media?parent=6370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/categories?post=6370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abbabrasil.org.br\/en\/wp-json\/wp\/v2\/tags?post=6370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}